{"id":484,"date":"2025-04-19T07:05:06","date_gmt":"2025-04-19T07:05:06","guid":{"rendered":"https:\/\/livewp.site\/wp\/md\/lirena\/?page_id=484"},"modified":"2021-03-05T08:38:25","modified_gmt":"2021-03-05T08:38:25","slug":"contacts","status":"publish","type":"page","link":"https:\/\/livewp.site\/wp\/md\/lirena\/contacts\/","title":{"rendered":"Contacts"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"484\" class=\"elementor elementor-484\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8b1b017 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8b1b017\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7611ac9\" data-id=\"7611ac9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2bc603a overflow_hidden elementor-widget elementor-widget-gt3-core-googlemap\" data-id=\"2bc603a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"gt3-core-googlemap.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t<div class=\"gt3_core_elementor_map \">\n\t\t<div class=\"map-core-canvas map-id-2461637d\"><\/div>\n\t\t\t\t\t<div class=\"content_core_popup\">\n\t\t\t\t<div class=\"map_info_marker\">\n\t\t\t\t\t<div class=\"map_info_marker_content\"><div class=\"marker_info_street\">121 Waldeck Street, NY, USA<\/div><\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<script>\n\t\t\tfunction gt3_core_initialize_map_2461637d() {\n\t\t\t\t\t\t\t\t\tvar styleArray = [{\"featureType\":\"water\",\"elementType\":\"geometry\",\"stylers\":[{\"color\":\"#e9e9e9\"},{\"lightness\":17}]},{\"featureType\":\"landscape\",\"elementType\":\"geometry\",\"stylers\":[{\"color\":\"#f5f5f5\"},{\"lightness\":20}]},{\"featureType\":\"road.highway\",\"elementType\":\"geometry.fill\",\"stylers\":[{\"color\":\"#ffffff\"},{\"lightness\":17}]},{\"featureType\":\"road.highway\",\"elementType\":\"geometry.stroke\",\"stylers\":[{\"color\":\"#ffffff\"},{\"lightness\":29},{\"weight\":0.2}]},{\"featureType\":\"road.arterial\",\"elementType\":\"geometry\",\"stylers\":[{\"color\":\"#ffffff\"},{\"lightness\":18}]},{\"featureType\":\"road.local\",\"elementType\":\"geometry\",\"stylers\":[{\"color\":\"#ffffff\"},{\"lightness\":16}]},{\"featureType\":\"poi\",\"elementType\":\"geometry\",\"stylers\":[{\"color\":\"#f5f5f5\"},{\"lightness\":21}]},{\"featureType\":\"poi.park\",\"elementType\":\"geometry\",\"stylers\":[{\"color\":\"#dedede\"},{\"lightness\":21}]},{\"elementType\":\"labels.text.stroke\",\"stylers\":[{\"visibility\":\"on\"},{\"color\":\"#ffffff\"},{\"lightness\":16}]},{\"elementType\":\"labels.text.fill\",\"stylers\":[{\"saturation\":36},{\"color\":\"#333333\"},{\"lightness\":40}]},{\"elementType\":\"labels.icon\",\"stylers\":[{\"visibility\":\"off\"}]},{\"featureType\":\"transit\",\"elementType\":\"geometry\",\"stylers\":[{\"color\":\"#f2f2f2\"},{\"lightness\":19}]},{\"featureType\":\"administrative\",\"elementType\":\"geometry.fill\",\"stylers\":[{\"color\":\"#fefefe\"},{\"lightness\":20}]},{\"featureType\":\"administrative\",\"elementType\":\"geometry.stroke\",\"stylers\":[{\"color\":\"#fefefe\"},{\"lightness\":17},{\"weight\":1.2}]}];\n\t\t\t\t\n\t\t\t\tdefinePopupClass();\n\n\t\t\t\tvar myLatlng = new google.maps.LatLng(40.626691, -74.000690);\n\n\t\t\t\tvar mapOptions = {\n\t\t\t\t\tzoom: 14,\n\t\t\t\t\tscrollwheel: false,\n\t\t\t\t\tcenter: myLatlng,\n\t\t\t\t\tmapTypeId: google.maps.MapTypeId.ROADMAP,\n\t\t\t\t\tstyles: styleArray\n\t\t\t\t};\n\n\t\t\t\tvar map = new google.maps.Map(document.getElementsByClassName('map-id-2461637d')[0], mapOptions);\n\n\t\t\t\tvar marker = new google.maps.Marker({\n\t\t\t\t\t position: myLatlng,\n\t\t\t\t\t map: map,\n\t\t\t\t\t icon: 'https:\/\/s3.amazonaws.com\/gt3themes\/gmap\/lirena.png'\n\t\t\t\t});\n\n\t\t\t\t\t\t\t\tpopup = new Popup(\n\t\t\t\t\tmyLatlng,\n\t\t\t\t\tdocument.getElementsByClassName('content_core_popup')[0]);\n\t\t\t\tpopup.setMap(map);\n\t\t\t\t\n\t\t\t}\n\n\t\t\tfunction definePopupClass() {\n\t\t\t\tPopup = function(position, content) {\n\t\t\t\t\tthis.position = position;\n\n\t\t\t\t\tcontent.classList.add('popup-bubble-content');\n\n\t\t\t\t\tvar pixelOffset = document.createElement('div');\n\t\t\t\t\tpixelOffset.classList.add('popup-bubble-anchor');\n\t\t\t\t\tpixelOffset.appendChild(content);\n\n\t\t\t\t\tthis.anchor = document.createElement('div');\n\t\t\t\t\tthis.anchor.classList.add('popup-tip-anchor');\n\t\t\t\t\tthis.anchor.appendChild(pixelOffset);\n\n\t\t\t\t\tthis.stopEventPropagation();\n\t\t\t\t};\n\t\t\t\tPopup.prototype = Object.create(google.maps.OverlayView.prototype);\n\n\t\t\t\tPopup.prototype.onAdd = function() {\n\t\t\t\t\tthis.getPanes().floatPane.appendChild(this.anchor);\n\t\t\t\t};\n\n\t\t\t\tPopup.prototype.onRemove = function() {\n\t\t\t\t\tif (this.anchor.parentElement) {\n\t\t\t\t\t\tthis.anchor.parentElement.removeChild(this.anchor);\n\t\t\t\t\t}\n\t\t\t\t};\n\n\t\t\t\tPopup.prototype.draw = function() {\n\t\t\t\t\tvar divPosition = this.getProjection().fromLatLngToDivPixel(this.position);\n\t\t\t\t\tvar display =\n\t\t\t\t\t\tMath.abs(divPosition.x) < 4000 && Math.abs(divPosition.y) < 4000 ?\n                                    'block' :\n                                    'none';\n\n\t\t\t\t\tif (display === 'block') {\n\t\t\t\t\tthis.anchor.style.left = divPosition.x + 'px';\n\t\t\t\t\tthis.anchor.style.top = divPosition.y + 'px';\n\t\t\t\t}\n\t\t\t\tif (this.anchor.style.display !== display) {\n\t\t\t\t\tthis.anchor.style.display = display;\n\t\t\t\t}\n\t\t\t};\n\n\t\t\tPopup.prototype.stopEventPropagation = function() {\n\t\t\t\tvar anchor = this.anchor;\n\t\t\t\tanchor.style.cursor = 'auto';\n\t\t\t\t\t['click', 'dblclick', 'contextmenu', 'wheel', 'mousedown', 'touchstart', 'pointerdown'].forEach(function(event) {\n\t\t\t\t\t\tanchor.addEventListener(event, function(e) {\n\t\t\t\t\t\t\te.stopPropagation();\n\t\t\t\t\t\t});\n\t\t\t\t\t});\n\t\t\t};\n\t\t\t}\n\t\t\tjQuery(document).ready(function(){\n\t\t\t\tif ('google' in window) {\n\t\t\t\t\tgt3_core_initialize_map_2461637d();\n\t\t\t\t} else {\n\t\t\t\t\tsetTimeout(function () {\n\t\t\t\t\t\tif ('google' in window) {\n\t\t\t\t\t\t\tgt3_core_initialize_map_2461637d();\n\t\t\t\t\t\t}\n\t\t\t\t\t}, 3000);\n\t\t\t\t}\n\t\t\t});\n\t\t<\/script>\n\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4f8ee99 elementor-widget elementor-widget-spacer\" data-id=\"4f8ee99\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-510fbac elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"510fbac\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-8172c45\" data-id=\"8172c45\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c4ab102 elementor-widget elementor-widget-heading\" data-id=\"c4ab102\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Get in Touch<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e2732b4 elementor-widget elementor-widget-text-editor\" data-id=\"e2732b4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Cibo mollis similique an duo, quo ex sale doctus insolens. Tale facilisi electram no vim. Ad ius sonet forensibus.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-622c5a8\" data-id=\"622c5a8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-edba46f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"edba46f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4dea33a\" data-id=\"4dea33a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4af667d elementor-widget elementor-widget-spacer\" data-id=\"4af667d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-aef7e09 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"aef7e09\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-384f607\" data-id=\"384f607\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5849b45 elementor-widget elementor-widget-heading\" data-id=\"5849b45\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Make an Appointment<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1bcc2e8 elementor-widget elementor-widget-shortcode\" data-id=\"1bcc2e8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f6-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"6\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/wp\/md\/lirena\/wp-json\/wp\/v2\/pages\/484#wpcf7-f6-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"6\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.5\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f6-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class=\"row\">\n\t<div class=\"name-wrapper span6\">\n\t\t<p><label><span class=\"label\">Name<\/span><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span><\/label>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"tel-wrapper span6\">\n\t\t<p><label><span class=\"label\">Phone<\/span><span class=\"wpcf7-form-control-wrap\" data-name=\"your-tel\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"tel\" name=\"your-tel\" \/><\/span><\/label>\n\t\t<\/p>\n\t<\/div>\n<\/div>\n<div class=\"row\">\n\t<div class=\"procedure-wrapper span6\">\n\t\t<p><label><span class=\"label\">Procedure<\/span><span class=\"wpcf7-form-control-wrap\" data-name=\"menu-procedure_100\"><select class=\"wpcf7-form-control wpcf7-select\" aria-invalid=\"false\" name=\"menu-procedure_100\"><option value=\"Facials\">Facials<\/option><option value=\"Body Treatments\">Body Treatments<\/option><option value=\"Waxing\">Waxing<\/option><option value=\"Massage\">Massage<\/option><option value=\"Finishing Touches\">Finishing Touches<\/option><option value=\"Hands &amp; Feet\">Hands &amp; Feet<\/option><option value=\"Tea Therapy\">Tea Therapy<\/option><option value=\"Aroma Therapy\">Aroma Therapy<\/option><\/select><\/span><\/label>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"date-wrapper span6\">\n\t\t<p><label><span class=\"wpcf7-form-control-wrap\" data-name=\"date-979\"><input class=\"wpcf7-form-control wpcf7-date wpcf7-validates-as-date walcf7-datetimepicker\" aria-invalid=\"false\" value=\"\" type=\"date\" name=\"date-979\" \/><\/span><\/label>\n\t\t<\/p>\n\t<\/div>\n<\/div>\n<div class=\"message-wrapper\">\n\t<p><label><span class=\"label\">Message<\/span><span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"4\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"your-message\"><\/textarea><\/span><\/label>\n\t<\/p>\n<\/div>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Book Now\" \/>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-393528e\" data-id=\"393528e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f5083c5 elementor-widget elementor-widget-heading\" data-id=\"f5083c5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Contact Info<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-419ce04 elementor-widget elementor-widget-text-editor\" data-id=\"419ce04\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 500; color: #541f5c;\" class=\"gt3_font-weight\">Phone:<\/span><br \/>8 800 563 423<\/p><p><span style=\"font-weight: 500; color: #541f5c;\" class=\"gt3_font-weight\">Address:<\/span><br \/>121 Waldeck Street, NY, USA<\/p><p><span style=\"font-weight: 500; color: #541f5c;\" class=\"gt3_font-weight\">Email:<\/span><br \/>email@example.com<\/p><p><span style=\"font-weight: 500; color: #541f5c;\" class=\"gt3_font-weight\">Opening hours:\u00a0<\/span><br \/>Monday to Friday: 09:00 am &#8211; 08:00 pm<br \/>Saturday to Sunday: 09:00 am &#8211; 06:00 pm<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8ee9c18 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8ee9c18\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-22ac665\" data-id=\"22ac665\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6981f7d elementor-widget elementor-widget-spacer\" data-id=\"6981f7d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>121 Waldeck Street, NY, USA Get in Touch Cibo mollis similique an duo, quo ex sale doctus insolens. Tale facilisi electram no vim. Ad ius sonet forensibus. Make an Appointment Contact Info Phone: 8 800 563 423 Address: 121 Waldeck Street, NY, USA Email: email@example.com Opening hours:&nbsp; Monday to Friday: 09:00 am &#8211; 08:00 pm [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-484","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/livewp.site\/wp\/md\/lirena\/wp-json\/wp\/v2\/pages\/484","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/livewp.site\/wp\/md\/lirena\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/livewp.site\/wp\/md\/lirena\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/livewp.site\/wp\/md\/lirena\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/livewp.site\/wp\/md\/lirena\/wp-json\/wp\/v2\/comments?post=484"}],"version-history":[{"count":0,"href":"https:\/\/livewp.site\/wp\/md\/lirena\/wp-json\/wp\/v2\/pages\/484\/revisions"}],"wp:attachment":[{"href":"https:\/\/livewp.site\/wp\/md\/lirena\/wp-json\/wp\/v2\/media?parent=484"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}